{"id":591,"date":"2024-04-29T10:51:35","date_gmt":"2024-04-29T09:51:35","guid":{"rendered":"https:\/\/www.talence.it\/?p=591"},"modified":"2024-04-29T12:51:28","modified_gmt":"2024-04-29T11:51:28","slug":"interrogazione-dei-dati-sanitari","status":"publish","type":"post","link":"https:\/\/www.talence.it\/es\/2024\/04\/interrogazione-dei-dati-sanitari\/","title":{"rendered":"La pregunta de los datos de salud"},"content":{"rendered":"<div id='layer_slider_1'  class='avia-layerslider main_color avia-shadow  avia-builder-el-0  el_before_av_section  avia-builder-el-first  container_wrap fullsize'  style='height: 721px; max-width: 1280px; margin: 0 auto;'  ><\/div>\n<div id='large'  class='avia-section av-4gkfd3-f77f842bc199d8324df339780cc77a90 alternate_color avia-section-default avia-no-border-styling  avia-builder-el-1  el_after_av_layerslider  el_before_av_section  hide-on-small avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-591'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-47qqmv-efe6257a9ec01eb31cf0ff9e5d678c5a sc-av_one_fifth av-equal-height-column-flextable shadow-not-animated'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-47qqmv-efe6257a9ec01eb31cf0ff9e5d678c5a\">\n@keyframes av_boxShadowEffect_av-47qqmv-efe6257a9ec01eb31cf0ff9e5d678c5a-row {\n0%   { box-shadow:  0 0 0 0 #444444; opacity: 1; }\n100% { box-shadow:  0 0 10px 0 #444444; opacity: 1; }\n}\n.flex_column_table.av-equal-height-column-flextable.av-47qqmv-efe6257a9ec01eb31cf0ff9e5d678c5a{\nbox-shadow: 0 0 10px 0 #444444;\n}\n.flex_column.av-47qqmv-efe6257a9ec01eb31cf0ff9e5d678c5a{\nborder-radius:0 0 0 0;\npadding:10px 10px 10px 10px;\nbackground-color:#4d21b4;\nbackground:linear-gradient( to bottom right, #4d21b4, #652dc1, #622fd9 );\n}\n<\/style>\n<div  class='flex_column av-47qqmv-efe6257a9ec01eb31cf0ff9e5d678c5a av_one_fifth  avia-builder-el-2  el_before_av_three_fifth  avia-builder-el-first  first no_margin flex_column_table_cell av-equal-height-column av-align-middle'     ><div  class='avia-button-wrap av-3zve0n-27aec2e4e0a658911eabbf14c7ac946c-wrap avia-button-center  avia-builder-el-3  avia-builder-el-no-sibling'><a href='https:\/\/www.talence.it\/es\/'  class='avia-button av-3zve0n-27aec2e4e0a658911eabbf14c7ac946c av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-center av-icon-on-hover avia-color-light'   aria-label=\"Inicial\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue821' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Inicial<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3voe27-be2e14b8313f1d39ac6f6e7ed48d7271\">\n@keyframes av_boxShadowEffect_av-3voe27-be2e14b8313f1d39ac6f6e7ed48d7271-row {\n0%   { box-shadow:  0 0 0 0 #444444; opacity: 1; }\n100% { box-shadow:  0 0 10px 0 #444444; opacity: 1; }\n}\n.flex_column_table.av-equal-height-column-flextable.av-3voe27-be2e14b8313f1d39ac6f6e7ed48d7271{\nbox-shadow: 0 0 10px 0 #444444;\n}\n.flex_column.av-3voe27-be2e14b8313f1d39ac6f6e7ed48d7271{\nborder-radius:0 0 0 0;\npadding:10px 10px 10px 10px;\nbackground-color:#4d21b4;\nbackground:linear-gradient( to bottom right, #4d21b4, #652dc1, #622fd9 );\n}\n<\/style>\n<div  class='flex_column av-3voe27-be2e14b8313f1d39ac6f6e7ed48d7271 av_three_fifth  avia-builder-el-4  el_after_av_one_fifth  el_before_av_one_fifth  no_margin flex_column_table_cell av-equal-height-column av-align-middle'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3nqn0v-5844c589350b31696690e426a5fc7a24\">\n#top .av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24{\nmargin:50px 50px 50px 50px;\ncolor:#cccccc;\nfont-size:30px;\n}\nbody .av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24 .av-special-heading-tag{\nfont-size:30px;\npadding:20px 0 40px 0;\n}\n.av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24 .special-heading-inner-border{\nborder-color:#cccccc;\n}\n.av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24 .av-subheading{\nfont-size:20px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-3nqn0v-5844c589350b31696690e426a5fc7a24 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-3nqn0v-5844c589350b31696690e426a5fc7a24 av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-5  avia-builder-el-no-sibling  av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >La pregunta de los datos de salud<\/h1><div class='av_custom_color av-subheading av-subheading_below'><p>Nuestro software de votaci\u00f3n de los datos de salud es totalmente personalizable y permite linterrogazione datos de salud presneti en las historias cl\u00ednicas digitalizadas en una manera simple y efectiva<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3it8g7-096b0dc06ce26418c58ff6ad9b103b1c\">\n@keyframes av_boxShadowEffect_av-3it8g7-096b0dc06ce26418c58ff6ad9b103b1c-row {\n0%   { box-shadow:  0 0 0 0 #444444; opacity: 1; }\n100% { box-shadow:  0 0 10px 0 #444444; opacity: 1; }\n}\n.flex_column_table.av-equal-height-column-flextable.av-3it8g7-096b0dc06ce26418c58ff6ad9b103b1c{\nbox-shadow: 0 0 10px 0 #444444;\n}\n.flex_column.av-3it8g7-096b0dc06ce26418c58ff6ad9b103b1c{\nborder-radius:0 0 0 0;\npadding:10px 10px 10px 10px;\nbackground-color:#4d21b4;\nbackground:linear-gradient( to bottom right, #4d21b4, #652dc1, #622fd9 );\n}\n<\/style>\n<div  class='flex_column av-3it8g7-096b0dc06ce26418c58ff6ad9b103b1c av_one_fifth  avia-builder-el-6  el_after_av_three_fifth  el_before_av_one_half  no_margin flex_column_table_cell av-equal-height-column av-align-middle'     ><div  class='avia-button-wrap av-3g5zfr-9e9dfc962c9138c74e1c3833e995ff95-wrap avia-button-center  avia-builder-el-7  avia-builder-el-no-sibling'><a href='https:\/\/www.talence.it\/es\/servizi\/'  class='avia-button av-3g5zfr-9e9dfc962c9138c74e1c3833e995ff95 av-link-btn avia-icon_select-yes-right-icon avia-size-large avia-position-center av-icon-on-hover avia-color-light'   aria-label=\"Servicios\"><span class='avia_iconbox_title' >Servicios<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue856' data-av_iconfont='entypo-fontello' ><\/span><\/a><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-37rdx3-7a86bcaa0a3f3cee218415435d58f564 sc-av_one_half av-equal-height-column-flextable'><div  class='flex_column av-37rdx3-7a86bcaa0a3f3cee218415435d58f564 av_one_half  avia-builder-el-8  el_after_av_one_fifth  el_before_av_one_half  first flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvkupxn9-19ec4bc5736d84a0f28a75a2da0df790\">\n#top .av-special-heading.av-lvkupxn9-19ec4bc5736d84a0f28a75a2da0df790{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lvkupxn9-19ec4bc5736d84a0f28a75a2da0df790 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-lvkupxn9-19ec4bc5736d84a0f28a75a2da0df790 .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-lvkupxn9-19ec4bc5736d84a0f28a75a2da0df790 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lvkupxn9-19ec4bc5736d84a0f28a75a2da0df790 av-special-heading-h1  avia-builder-el-9  el_before_av_toggle_container  avia-builder-el-first'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >Caracter\u00edsticas clave<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-31r23z-710cd57a1b282e9011a2213aeb8248e6\">\n#top .togglecontainer.av-31r23z-710cd57a1b282e9011a2213aeb8248e6 p.toggler{\nfont-size:25px;\n}\n#top .togglecontainer.av-31r23z-710cd57a1b282e9011a2213aeb8248e6 .toggle_wrap .toggle_content{\nfont-size:20px;\n}\n<\/style>\n<div  class='togglecontainer av-31r23z-710cd57a1b282e9011a2213aeb8248e6 av-elegant-toggle  avia-builder-el-10  el_after_av_heading  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-2y7xpz-06e7e3024947ef882b6c8a0a5c0f6cc0'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-1' data-fake-id='#toggle-id-1' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1' data-slide-speed=\"200\" data-title=\"Introduzione\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Introduzione\" data-aria_expanded=\"Click to collapse: Introduzione\">Introducci\u00f3n<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' aria-labelledby='toggle-toggle-id-1' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>La inteligencia Artificial se est\u00e1 convirtiendo en parte de diversas aplicaciones en el campo de la Salud y, en particular, el chatbot son una de las aplicaciones m\u00e1s comunes de la inteligencia artificial, el uso en el servicio de atenci\u00f3n al cliente. La inteligencia artificial de conversaci\u00f3n es un conjunto de tecnolog\u00edas, tales como NLP (natural language processing), aprendizaje autom\u00e1tico y la inteligencia artificial de voz con el que crear interfaces de chat de voz o para permitir conversaciones automatizado, con clientes similares a las humanas. Adem\u00e1s, la creciente adopci\u00f3n de la tecnolog\u00eda PARA apoyar a nuestros clientes en todos los sectores, est\u00e1 impulsando el crecimiento del mercado de Voicebot. En esencia, se puede implementar de Conversaci\u00f3n Chatbot y Voicebot en los canales dirigidos a los clientes a automatizar las conversaciones con los clientes, para interpretar las necesidades de los clientes y optimizar el trabajo de la agente en el call center, que ayuda a reducir el tiempo promedio para la gesti\u00f3n de la demanda y minimizar los costes.<\/p>\n<p>En contraposici\u00f3n a este tipo de operaci\u00f3n, nuestro servicio en su lugar, utiliza la l\u00f3gica de tipo voicebot, no simplemente para apoyar el servicio a los pacientes, sino para dar respuestas concretas, y la informaci\u00f3n oportuna a los profesionales de la salud que trabajan en el campo. Este resultado, adem\u00e1s de las tecnolog\u00edas de la PNL y MASTER est\u00e1 relacionada con la cantidad y calidad de los datos digitalizados disponibles en forma estructurada, que ponga el sistema en un estado para proporcionar los profesionales de la salud con informaci\u00f3n cr\u00edtica sobre los pacientes, que permita la comunicaci\u00f3n con los pacientes de manera m\u00e1s eficaz, acelerar el proceso de diagn\u00f3stico y, en general, le permiten ofrecer una mejor atenci\u00f3n y m\u00e1s eficiente.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2rgo07-8e2f8cb72dedf99a2a270d0008c989cc'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-2' data-fake-id='#toggle-id-2' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2' data-slide-speed=\"200\" data-title=\"Cos\u2019\u00e8 un voicebot a supporto degli operatori?\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Cos\u2019\u00e8 un voicebot a supporto degli operatori?\" data-aria_expanded=\"Click to collapse: Cos\u2019\u00e8 un voicebot a supporto degli operatori?\">\u00bfQu\u00e9 es un voicebot para apoyar a los operadores?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' aria-labelledby='toggle-toggle-id-2' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Un voicebot es un programa interactivo que utiliza la Inteligencia Artificial y el entendimiento del lenguaje natural (NLU) basado en el Gran Modelo de Lenguaje (LLM) en orden a interpretar linput de una pareja, esta tecnolog\u00eda se denomina como &#034;IVR conversacional&#034;.<\/p>\n<p>El voicebot utilizando el reconocimiento de voz de la entrada, que se ha traducido en el texto (lo que com\u00fanmente se conoce como voz-a-texto, o STT) para la recopilaci\u00f3n de preguntas y la l\u00f3gica de un texto-a-voz (TTS) para entender el recibo de la solicitud y responder de manera adecuada en una lengua natural.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-lvku9umg-c499963c5319fc48fbc0bde7f2f983f6'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-3' data-fake-id='#toggle-id-3' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3' data-slide-speed=\"200\" data-title=\"Differenza tra voicebot e chatbot\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Differenza tra voicebot e chatbot\" data-aria_expanded=\"Click to collapse: Differenza tra voicebot e chatbot\">Diferencia entre voicebot y chatbot<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' aria-labelledby='toggle-toggle-id-3' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Como voicebot en l\u00ednea, un chatbot es una interfaz que es conversacional dotado de Inteligencia Artificial que puede ser usado para automatizar y optimizar las interacciones con el servicio de atenci\u00f3n al cliente, durante el di\u00e1logo, el inicial.<\/p>\n<p>Mientras que el voicebot son capaces de interpretar la voz hablada y para comunicarse directamente con el operador (Alexa es un ejemplo de voicebot), el chatbot son soluciones que se basan en mensajes de texto. Interpretar, por lo tanto, las palabras escritas, y responder con el mismo m\u00e9todo, de tipo texto. De esta manera usted va a crear una interacci\u00f3n entre el robot y el usuario que imita muy bien a las conversaciones de mensajer\u00eda entre personas reales.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-285g87-dee3255c17a2b346889c632a0f15b24b'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-4' data-fake-id='#toggle-id-4' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-4' data-slide-speed=\"200\" data-title=\"Approcci innovativo basato su voicebot\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Approcci innovativo basato su voicebot\" data-aria_expanded=\"Click to collapse: Approcci innovativo basato su voicebot\">Los enfoques basados en la innovadora voicebot<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-4' aria-labelledby='toggle-toggle-id-4' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>El coraz\u00f3n del sistema es representado por el vector de codificaci\u00f3n de la base de datos de una gr\u00e1fica de los conocimientos de la salud la informaci\u00f3n recopilada de los registros m\u00e9dicos electr\u00f3nicos de los pacientes y hace que su b\u00fasqueda, a trav\u00e9s de la voicebot. Claramente el nivel de las respuestas obtenidas est\u00e1 estrechamente relacionado con la calidad y cantidad de los datos cl\u00ednicos disponibles en la base de datos, en este sentido, un propeduetica base de un modelo similar es, inevitablemente, un proyecto para la normalizaci\u00f3n y el modelado de los datos cl\u00ednicos disponibles en un centro de salud.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-lrkuk2gs-d29e57665035a54eb20f7f6a1b0eb0d2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-5' data-fake-id='#toggle-id-5' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-5' data-slide-speed=\"200\" data-title=\"Estendibilit\u00e0 del sistema basato su voicebot\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Estendibilit\u00e0 del sistema basato su voicebot\" data-aria_expanded=\"Click to collapse: Estendibilit\u00e0 del sistema basato su voicebot\">La extensibilidad del sistema basado en la voicebot<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-5' aria-labelledby='toggle-toggle-id-5' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Como se defini\u00f3 anteriormente, es posible integrar los dos componentes fondamantali tecnolog\u00eda voicebot que es, la etapa inicial de la investigaci\u00f3n (voz-a-texto), y la respuesta final (text-to-speech( aplicaci\u00f3n a otros casos de uso de, por ejemplo, para la interacci\u00f3n con el DSS para apoyo a la prescripci\u00f3n de medicamentos.<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-257khz-3f52a3bc51d1c4a16241a3a142d97117 av_one_half  avia-builder-el-11  el_after_av_one_half  el_before_av_hr  flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1wikr3-5501d650ba0f69b1a894d9f32c7b6f4d\">\n.avia-image-container.av-1wikr3-5501d650ba0f69b1a894d9f32c7b6f4d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1wikr3-5501d650ba0f69b1a894d9f32c7b6f4d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1wikr3-5501d650ba0f69b1a894d9f32c7b6f4d av-styling- avia-align-center  avia-builder-el-12  el_before_av_image  avia-builder-el-first'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image- avia-img-lazy-loading-not- avia_image' src=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta-1.jpg\" alt='' title=''   itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lrkrxo1x-aebe6a38f9e96a2628ee628e0da30fbe\">\n.avia-image-container.av-lrkrxo1x-aebe6a38f9e96a2628ee628e0da30fbe img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lrkrxo1x-aebe6a38f9e96a2628ee628e0da30fbe .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lrkrxo1x-aebe6a38f9e96a2628ee628e0da30fbe av-styling- avia-align-center  avia-builder-el-13  el_after_av_image  avia-builder-el-last'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-464 avia-img-lazy-loading-not-464 avia_image' src=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta.jpg\" alt='' title='A la escucha'  height=\"464\" width=\"696\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta.jpg 696w, https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta-300x200.jpg 300w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/div><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1rh7fj-f4da5a45be6784d7bc4fa334ae8d37cf\">\n#top .hr.hr-invisible.av-1rh7fj-f4da5a45be6784d7bc4fa334ae8d37cf{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-1rh7fj-f4da5a45be6784d7bc4fa334ae8d37cf hr-invisible  avia-builder-el-14  el_after_av_one_half  avia-builder-el-last'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='small'  class='avia-section av-lvkv4ufm-8b4a31f26de344b1570c2068a0cb7527 alternate_color avia-section-default avia-no-border-styling  avia-builder-el-15  el_after_av_section  el_before_av_section  hide-on-large avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-591'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-535kif-f69d9a6c258f72a920c3a3f8f65e98b7 sc-av_one_fifth av-equal-height-column-flextable shadow-not-animated'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-535kif-f69d9a6c258f72a920c3a3f8f65e98b7\">\n@keyframes av_boxShadowEffect_av-535kif-f69d9a6c258f72a920c3a3f8f65e98b7-row {\n0%   { box-shadow:  0 0 0 0 #444444; opacity: 1; }\n100% { box-shadow:  0 0 10px 0 #444444; opacity: 1; }\n}\n.flex_column_table.av-equal-height-column-flextable.av-535kif-f69d9a6c258f72a920c3a3f8f65e98b7{\nbox-shadow: 0 0 10px 0 #444444;\n}\n.flex_column.av-535kif-f69d9a6c258f72a920c3a3f8f65e98b7{\nborder-radius:0 0 0 0;\npadding:10px 10px 10px 10px;\nbackground-color:#4d21b4;\nbackground:linear-gradient( to bottom right, #4d21b4, #652dc1, #622fd9 );\n}\n<\/style>\n<div  class='flex_column av-535kif-f69d9a6c258f72a920c3a3f8f65e98b7 av_one_fifth  avia-builder-el-16  el_before_av_three_fifth  avia-builder-el-first  first no_margin flex_column_table_cell av-equal-height-column av-align-middle'     ><div  class='avia-button-wrap av-4ul8z3-58c5e284671f703c9156e551b3d5871c-wrap avia-button-center  avia-builder-el-17  avia-builder-el-no-sibling'><a href='https:\/\/www.talence.it\/es\/'  class='avia-button av-4ul8z3-58c5e284671f703c9156e551b3d5871c av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-center av-icon-on-hover avia-color-light'   aria-label=\"Inicial\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue821' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Inicial<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4o4mqv-f7edfb1892680b0356a2a145056fce2a\">\n@keyframes av_boxShadowEffect_av-4o4mqv-f7edfb1892680b0356a2a145056fce2a-row {\n0%   { box-shadow:  0 0 0 0 #444444; opacity: 1; }\n100% { box-shadow:  0 0 10px 0 #444444; opacity: 1; }\n}\n.flex_column_table.av-equal-height-column-flextable.av-4o4mqv-f7edfb1892680b0356a2a145056fce2a{\nbox-shadow: 0 0 10px 0 #444444;\n}\n.flex_column.av-4o4mqv-f7edfb1892680b0356a2a145056fce2a{\nborder-radius:0 0 0 0;\npadding:10px 10px 10px 10px;\nbackground-color:#4d21b4;\nbackground:linear-gradient( to bottom right, #4d21b4, #652dc1, #622fd9 );\n}\n<\/style>\n<div  class='flex_column av-4o4mqv-f7edfb1892680b0356a2a145056fce2a av_three_fifth  avia-builder-el-18  el_after_av_one_fifth  el_before_av_one_fifth  no_margin flex_column_table_cell av-equal-height-column av-align-middle'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4jziov-38728c78fb9171f09be90aeb015747a2\">\n#top .av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2{\nmargin:50px 50px 50px 50px;\ncolor:#cccccc;\nfont-size:30px;\n}\nbody .av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2 .av-special-heading-tag{\nfont-size:30px;\npadding:20px 0 40px 0;\n}\n.av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2 .special-heading-inner-border{\nborder-color:#cccccc;\n}\n.av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2 .av-subheading{\nfont-size:20px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-4jziov-38728c78fb9171f09be90aeb015747a2 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-4jziov-38728c78fb9171f09be90aeb015747a2 av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-19  avia-builder-el-no-sibling  av-inherit-size'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >La pregunta de los datos de salud<\/h1><div class='av_custom_color av-subheading av-subheading_below'><p>Nuestro software de votaci\u00f3n de los datos de salud es totalmente personalizable y permite linterrogazione datos de salud presneti en las historias cl\u00ednicas digitalizadas en una manera simple y efectiva<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-fqltz-0f0c9e122e29666a8dd6f6ca3cbe1fde\">\n@keyframes av_boxShadowEffect_av-fqltz-0f0c9e122e29666a8dd6f6ca3cbe1fde-row {\n0%   { box-shadow:  0 0 0 0 #444444; opacity: 1; }\n100% { box-shadow:  0 0 10px 0 #444444; opacity: 1; }\n}\n.flex_column_table.av-equal-height-column-flextable.av-fqltz-0f0c9e122e29666a8dd6f6ca3cbe1fde{\nbox-shadow: 0 0 10px 0 #444444;\n}\n.flex_column.av-fqltz-0f0c9e122e29666a8dd6f6ca3cbe1fde{\nborder-radius:0 0 0 0;\npadding:10px 10px 10px 10px;\nbackground-color:#4d21b4;\nbackground:linear-gradient( to bottom right, #4d21b4, #652dc1, #622fd9 );\n}\n<\/style>\n<div  class='flex_column av-fqltz-0f0c9e122e29666a8dd6f6ca3cbe1fde av_one_fifth  avia-builder-el-20  el_after_av_three_fifth  el_before_av_one_full  no_margin flex_column_table_cell av-equal-height-column av-align-middle'     ><div  class='avia-button-wrap av-4a05yn-246fd75828b7461a269b1fbcc4eba453-wrap avia-button-center  avia-builder-el-21  avia-builder-el-no-sibling'><a href='https:\/\/www.talence.it\/es\/servizi\/'  class='avia-button av-4a05yn-246fd75828b7461a269b1fbcc4eba453 av-link-btn avia-icon_select-yes-right-icon avia-size-large avia-position-center av-icon-on-hover avia-color-light'   aria-label=\"Servicios\"><span class='avia_iconbox_title' >Servicios<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue856' data-av_iconfont='entypo-fontello' ><\/span><\/a><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div  class='flex_column av-43eur3-b62c60554ce0928f6c0f02fb314b4d26 av_one_full  avia-builder-el-22  el_after_av_one_fifth  el_before_av_one_full  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3wm1hb-9b08339e58833d3e0f9aa6eb77366a3d\">\n.avia-image-container.av-3wm1hb-9b08339e58833d3e0f9aa6eb77366a3d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-3wm1hb-9b08339e58833d3e0f9aa6eb77366a3d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-3wm1hb-9b08339e58833d3e0f9aa6eb77366a3d av-styling- avia-align-center  avia-builder-el-23  el_before_av_image  avia-builder-el-first'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image- avia-img-lazy-loading-not- avia_image' src=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta-1.jpg\" alt='' title=''   itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3sstnz-ef9ab964baba559803c55d59e5b264f8\">\n.avia-image-container.av-3sstnz-ef9ab964baba559803c55d59e5b264f8 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-3sstnz-ef9ab964baba559803c55d59e5b264f8 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-3sstnz-ef9ab964baba559803c55d59e5b264f8 av-styling- avia-align-center  avia-builder-el-24  el_after_av_image  avia-builder-el-last'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-464 avia-img-lazy-loading-not-464 avia_image' src=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta.jpg\" alt='' title='A la escucha'  height=\"464\" width=\"696\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta.jpg 696w, https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-ascolta-300x200.jpg 300w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/div><\/div><\/div><\/p><\/div><div class='flex_column_table av-czcj3-e63073bc3f67504e8783abdc7a40b67f sc-av_one_full av-equal-height-column-flextable'><div  class='flex_column av-czcj3-e63073bc3f67504e8783abdc7a40b67f av_one_full  avia-builder-el-25  el_after_av_one_full  el_before_av_hr  first flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3ez2on-6cbc65bcd811fa67d20164b45ef8ad07\">\n#top .av-special-heading.av-3ez2on-6cbc65bcd811fa67d20164b45ef8ad07{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-3ez2on-6cbc65bcd811fa67d20164b45ef8ad07 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-3ez2on-6cbc65bcd811fa67d20164b45ef8ad07 .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-3ez2on-6cbc65bcd811fa67d20164b45ef8ad07 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-3ez2on-6cbc65bcd811fa67d20164b45ef8ad07 av-special-heading-h1  avia-builder-el-26  el_before_av_toggle_container  avia-builder-el-first'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >Caracter\u00edsticas clave<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvkvgcc8-cb119674e369c87acc3830fd6a79b224\">\n#top .togglecontainer.av-lvkvgcc8-cb119674e369c87acc3830fd6a79b224 p.toggler{\nfont-size:35px;\n}\n#top .togglecontainer.av-lvkvgcc8-cb119674e369c87acc3830fd6a79b224 .toggle_wrap .toggle_content{\nfont-size:30px;\n}\n<\/style>\n<div  class='togglecontainer av-lvkvgcc8-cb119674e369c87acc3830fd6a79b224 av-elegant-toggle  avia-builder-el-27  el_after_av_heading  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-3aobp3-45098daa959dfb4012cd734bd3a9301d'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-6' data-fake-id='#toggle-id-6' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-6' data-slide-speed=\"200\" data-title=\"Introduzione\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Introduzione\" data-aria_expanded=\"Click to collapse: Introduzione\">Introducci\u00f3n<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-6' aria-labelledby='toggle-toggle-id-6' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>La inteligencia Artificial se est\u00e1 convirtiendo en parte de diversas aplicaciones en el campo de la Salud y, en particular, el chatbot son una de las aplicaciones m\u00e1s comunes de la inteligencia artificial, el uso en el servicio de atenci\u00f3n al cliente. La inteligencia artificial de conversaci\u00f3n es un conjunto de tecnolog\u00edas, tales como NLP (natural language processing), aprendizaje autom\u00e1tico y la inteligencia artificial de voz con el que crear interfaces de chat de voz o para permitir conversaciones automatizado, con clientes similares a las humanas. Adem\u00e1s, la creciente adopci\u00f3n de la tecnolog\u00eda PARA apoyar a nuestros clientes en todos los sectores, est\u00e1 impulsando el crecimiento del mercado de Voicebot. En esencia, se puede implementar de Conversaci\u00f3n Chatbot y Voicebot en los canales dirigidos a los clientes a automatizar las conversaciones con los clientes, para interpretar las necesidades de los clientes y optimizar el trabajo de la agente en el call center, que ayuda a reducir el tiempo promedio para la gesti\u00f3n de la demanda y minimizar los costes.<\/p>\n<p>En contraposici\u00f3n a este tipo de operaci\u00f3n, nuestro servicio en su lugar, utiliza la l\u00f3gica de tipo voicebot, no simplemente para apoyar el servicio a los pacientes, sino para dar respuestas concretas, y la informaci\u00f3n oportuna a los profesionales de la salud que trabajan en el campo. Este resultado, adem\u00e1s de las tecnolog\u00edas de la PNL y MASTER est\u00e1 relacionada con la cantidad y calidad de los datos digitalizados disponibles en forma estructurada, que ponga el sistema en un estado para proporcionar los profesionales de la salud con informaci\u00f3n cr\u00edtica sobre los pacientes, que permita la comunicaci\u00f3n con los pacientes de manera m\u00e1s eficaz, acelerar el proceso de diagn\u00f3stico y, en general, le permiten ofrecer una mejor atenci\u00f3n y m\u00e1s eficiente.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-30jqp3-79e76e7a399de570629191c86dc47617'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-7' data-fake-id='#toggle-id-7' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-7' data-slide-speed=\"200\" data-title=\"Cos\u2019\u00e8 un voicebot a supporto degli operatori?\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Cos\u2019\u00e8 un voicebot a supporto degli operatori?\" data-aria_expanded=\"Click to collapse: Cos\u2019\u00e8 un voicebot a supporto degli operatori?\">\u00bfQu\u00e9 es un voicebot para apoyar a los operadores?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-7' aria-labelledby='toggle-toggle-id-7' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Un voicebot es un programa interactivo que utiliza la Inteligencia Artificial y el entendimiento del lenguaje natural (NLU) basado en el Gran Modelo de Lenguaje (LLM) en orden a interpretar linput de una pareja, esta tecnolog\u00eda se denomina como &#034;IVR conversacional&#034;.<\/p>\n<p>El voicebot utilizando el reconocimiento de voz de la entrada, que se ha traducido en el texto (lo que com\u00fanmente se conoce como voz-a-texto, o STT) para la recopilaci\u00f3n de preguntas y la l\u00f3gica de un texto-a-voz (TTS) para entender el recibo de la solicitud y responder de manera adecuada en una lengua natural.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2xuthz-27cb9d5dbe00a4d8091695e654f391c4'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-8' data-fake-id='#toggle-id-8' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-8' data-slide-speed=\"200\" data-title=\"Differenza tra voicebot e chatbot\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Differenza tra voicebot e chatbot\" data-aria_expanded=\"Click to collapse: Differenza tra voicebot e chatbot\">Diferencia entre voicebot y chatbot<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-8' aria-labelledby='toggle-toggle-id-8' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Como voicebot en l\u00ednea, un chatbot es una interfaz que es conversacional dotado de Inteligencia Artificial que puede ser usado para automatizar y optimizar las interacciones con el servicio de atenci\u00f3n al cliente, durante el di\u00e1logo, el inicial.<\/p>\n<p>Mientras que el voicebot son capaces de interpretar la voz hablada y para comunicarse directamente con el operador (Alexa es un ejemplo de voicebot), el chatbot son soluciones que se basan en mensajes de texto. Interpretar, por lo tanto, las palabras escritas, y responder con el mismo m\u00e9todo, de tipo texto. De esta manera usted va a crear una interacci\u00f3n entre el robot y el usuario que imita muy bien a las conversaciones de mensajer\u00eda entre personas reales.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2oe8p3-8c3747e8498d7de1d158dc51d93f61ff'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-9' data-fake-id='#toggle-id-9' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-9' data-slide-speed=\"200\" data-title=\"Approcci innovativo basato su voicebot\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Approcci innovativo basato su voicebot\" data-aria_expanded=\"Click to collapse: Approcci innovativo basato su voicebot\">Los enfoques basados en la innovadora voicebot<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-9' aria-labelledby='toggle-toggle-id-9' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>El coraz\u00f3n del sistema es representado por el vector de codificaci\u00f3n de la base de datos de una gr\u00e1fica de los conocimientos de la salud la informaci\u00f3n recopilada de los registros m\u00e9dicos electr\u00f3nicos de los pacientes y hace que su b\u00fasqueda, a trav\u00e9s de la voicebot. Claramente el nivel de las respuestas obtenidas est\u00e1 estrechamente relacionado con la calidad y cantidad de los datos cl\u00ednicos disponibles en la base de datos, en este sentido, un propeduetica base de un modelo similar es, inevitablemente, un proyecto para la normalizaci\u00f3n y el modelado de los datos cl\u00ednicos disponibles en un centro de salud.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-9ebgv-14afa85f11e1ade24dc43004c5ce81ba'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-10' data-fake-id='#toggle-id-10' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-10' data-slide-speed=\"200\" data-title=\"Estendibilit\u00e0 del sistema basato su voicebot\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Estendibilit\u00e0 del sistema basato su voicebot\" data-aria_expanded=\"Click to collapse: Estendibilit\u00e0 del sistema basato su voicebot\">La extensibilidad del sistema basado en la voicebot<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-10' aria-labelledby='toggle-toggle-id-10' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Como se defini\u00f3 anteriormente, es posible integrar los dos componentes fondamantali tecnolog\u00eda voicebot que es, la etapa inicial de la investigaci\u00f3n (voz-a-texto), y la respuesta final (text-to-speech( aplicaci\u00f3n a otros casos de uso de, por ejemplo, para la interacci\u00f3n con el DSS para apoyo a la prescripci\u00f3n de medicamentos.<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2ckwyv-bffe9dbccb84df5bcc33d06f0d26cc26\">\n#top .hr.hr-invisible.av-2ckwyv-bffe9dbccb84df5bcc33d06f0d26cc26{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-2ckwyv-bffe9dbccb84df5bcc33d06f0d26cc26 hr-invisible  avia-builder-el-28  el_after_av_one_full  avia-builder-el-last'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-261hnr-77c580ec2e32db4a273251aa62b0c6a2\">\n.avia-section.av-261hnr-77c580ec2e32db4a273251aa62b0c6a2{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/rete-2.jpg);\nbackground-position:50% 50%;\nbackground-attachment:fixed;\n}\n.avia-section.av-261hnr-77c580ec2e32db4a273251aa62b0c6a2 .av-section-color-overlay{\nopacity:0.6;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-261hnr-77c580ec2e32db4a273251aa62b0c6a2 main_color avia-section-huge avia-no-border-styling  avia-builder-el-29  el_after_av_section  el_before_av_section  avia-full-stretch avia-bg-style-fixed av-section-color-overlay-active container_wrap fullsize'  data-section-bg-repeat='stretch'><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-591'><div class='entry-content-wrapper clearfix'><\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div><div id='large'  class='avia-section av-lvkv5b3f-22accc5780efa4e66d00f6cad16b3377 main_color avia-section-default avia-no-border-styling  avia-builder-el-30  el_after_av_section  el_before_av_section  hide-on-small avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-591'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7cfqv-8aec4e4f0e7324dd2a02ed0c436bc43b\">\n#top .hr.hr-invisible.av-7cfqv-8aec4e4f0e7324dd2a02ed0c436bc43b{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-7cfqv-8aec4e4f0e7324dd2a02ed0c436bc43b hr-invisible  avia-builder-el-31  el_before_av_one_half  avia-builder-el-first'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-1ke9yn-0d1ad969edf536cbb71afa1f8493afe8 sc-av_one_half av-equal-height-column-flextable'><div  class='flex_column av-1ke9yn-0d1ad969edf536cbb71afa1f8493afe8 av_one_half  avia-builder-el-32  el_after_av_hr  el_before_av_one_half  first flex_column_table_cell av-equal-height-column av-align-top'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1grx27-f75d97a0e24f7cb6336e640c71d649f8\">\n.avia-image-container.av-1grx27-f75d97a0e24f7cb6336e640c71d649f8 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1grx27-f75d97a0e24f7cb6336e640c71d649f8 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1grx27-f75d97a0e24f7cb6336e640c71d649f8 av-styling- avia-align-left  avia-builder-el-33  avia-builder-el-no-sibling'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-530 avia-img-lazy-loading-not-530 avia_image' src=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla.png\" alt='' title='Procesamiento Del Lenguaje Natural'  height=\"405\" width=\"720\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla.png 720w, https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla-300x169.png 300w, https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla-705x397.png 705w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-17mj1b-e8f50ff1ba513f424abfd0e073b54b8c av_one_half  avia-builder-el-34  el_after_av_one_half  el_before_av_hr  flex_column_table_cell av-equal-height-column av-align-top'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvkuqhx9-f8351c8540e6fa866fd4d24cfd22f379\">\n#top .av-special-heading.av-lvkuqhx9-f8351c8540e6fa866fd4d24cfd22f379{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lvkuqhx9-f8351c8540e6fa866fd4d24cfd22f379 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-lvkuqhx9-f8351c8540e6fa866fd4d24cfd22f379 .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-lvkuqhx9-f8351c8540e6fa866fd4d24cfd22f379 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lvkuqhx9-f8351c8540e6fa866fd4d24cfd22f379 av-special-heading-h1  avia-builder-el-35  el_before_av_toggle_container  avia-builder-el-first'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >Ventajas alcanzables<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvkv2yui-7b89b44bfb38b0aea5ad7c48d50801c7\">\n#top .togglecontainer.av-lvkv2yui-7b89b44bfb38b0aea5ad7c48d50801c7 p.toggler{\nfont-size:25px;\n}\n#top .togglecontainer.av-lvkv2yui-7b89b44bfb38b0aea5ad7c48d50801c7 .toggle_wrap .toggle_content{\nfont-size:20px;\n}\n<\/style>\n<div  class='togglecontainer av-lvkv2yui-7b89b44bfb38b0aea5ad7c48d50801c7 av-elegant-toggle  avia-builder-el-36  el_after_av_heading  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-lvkuun8u-c3cfcc6a6b5e410aa5258b509a767686'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-11' data-fake-id='#toggle-id-11' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-11' data-slide-speed=\"200\" data-title=\"Migliore interazione\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Migliore interazione\" data-aria_expanded=\"Click to collapse: Migliore interazione\">Mejor interacci\u00f3n<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-11' aria-labelledby='toggle-toggle-id-11' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Un voicebot IVR o interactiva ofrece una forma de comunicaci\u00f3n m\u00e1s suave y m\u00e1s r\u00e1pido al proporcionar una manera r\u00e1pida y eficiente la informaci\u00f3n que los cuidadores necesitan, sin obligarlos a buscar y visualizar los documentos, informes, notas, cl\u00ednica en la carpeta, etc.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-lvkuzecm-1c2bdbf76eccad441e3e87ccdad70c42'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-12' data-fake-id='#toggle-id-12' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-12' data-slide-speed=\"200\" data-title=\"Elevata disponibilit\u00e0\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Elevata disponibilit\u00e0\" data-aria_expanded=\"Click to collapse: Elevata disponibilit\u00e0\">Alta disponibilidad<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-12' aria-labelledby='toggle-toggle-id-12' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>El sistema se basa en voicebot es esencialmente siempre disponible las 24 horas del d\u00eda y 7 de las 7, por lo que los trabajadores de la salud pueden obtener respuestas a sus preguntas y sus problemas las 24 horas sobre 24, 7 d\u00edas sobre 7, sin tener que perder el tiempo buscando el finormazioni por los archivos electr\u00f3nicos est\u00e1n disponibles. Este elemento es muy importante en situaciones cr\u00edticas o de emergencia en tiempos dif\u00edciles, cuando es complejo para ser capaz de contar con el apoyo de la mayor\u00eda de los colegas del departamento o de otras estructuras.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-lvkv2ll2-ca6ea52719ab676a96cd77916c772c56'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-13' data-fake-id='#toggle-id-13' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-13' data-slide-speed=\"200\" data-title=\"Miglioramento degli outcome clinici\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Miglioramento degli outcome clinici\" data-aria_expanded=\"Click to collapse: Miglioramento degli outcome clinici\">La mejora de los resultados cl\u00ednicos<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-13' aria-labelledby='toggle-toggle-id-13' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>El sistema se basa en voicebot puede ayudar a reducir los tiempos de curaci\u00f3n y mejorar el nivel de precisi\u00f3n de la hip\u00f3tesis de diagnnostiche de apoyo y un mejor nivel de conocimiento en la elecci\u00f3n de la v\u00eda de atenci\u00f3n y terapias farmacol\u00f3gicas pueden ser m\u00e1s convenientes en un caso concreto.<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1ynitb-fa252f3424d0827c290e9fcbe1b45d69\">\n#top .hr.hr-invisible.av-1ynitb-fa252f3424d0827c290e9fcbe1b45d69{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-1ynitb-fa252f3424d0827c290e9fcbe1b45d69 hr-invisible  avia-builder-el-37  el_after_av_one_half  avia-builder-el-last'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='small'  class='avia-section av-lvkv5miq-8cf6ab28727783eb6164ec8cb76e9805 main_color avia-section-default avia-no-border-styling  avia-builder-el-38  el_after_av_section  el_before_av_section  hide-on-large avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-591'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6cnxr-88bd385f08e27ce229d71598ac9fa043\">\n#top .hr.hr-invisible.av-6cnxr-88bd385f08e27ce229d71598ac9fa043{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-6cnxr-88bd385f08e27ce229d71598ac9fa043 hr-invisible  avia-builder-el-39  el_before_av_one_full  avia-builder-el-first'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-1m4azj-474ab324ea71d683760a76ad12766f35 sc-av_one_full av-equal-height-column-flextable'><div  class='flex_column av-1m4azj-474ab324ea71d683760a76ad12766f35 av_one_full  avia-builder-el-40  el_after_av_hr  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-top'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1do4db-1d110c501421a95e9a0852e506bec193\">\n.avia-image-container.av-1do4db-1d110c501421a95e9a0852e506bec193 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1do4db-1d110c501421a95e9a0852e506bec193 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1do4db-1d110c501421a95e9a0852e506bec193 av-styling- avia-align-left  avia-builder-el-41  avia-builder-el-no-sibling'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-530 avia-img-lazy-loading-not-530 avia_image' src=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla.png\" alt='' title='Procesamiento Del Lenguaje Natural'  height=\"405\" width=\"720\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla.png 720w, https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla-300x169.png 300w, https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/AI-parla-705x397.png 705w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div  class='flex_column av-16qz8f-15cbaf874b49f791940b9c98eab9656d av_one_full  avia-builder-el-42  el_after_av_one_full  el_before_av_hr  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-12uiwn-2545ff0e97d6207c3de1d3254cc3815d\">\n#top .av-special-heading.av-12uiwn-2545ff0e97d6207c3de1d3254cc3815d{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-12uiwn-2545ff0e97d6207c3de1d3254cc3815d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-12uiwn-2545ff0e97d6207c3de1d3254cc3815d .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-12uiwn-2545ff0e97d6207c3de1d3254cc3815d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-12uiwn-2545ff0e97d6207c3de1d3254cc3815d av-special-heading-h1  avia-builder-el-43  el_before_av_toggle_container  avia-builder-el-first'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >Ventajas alcanzables<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lvkvei80-3845649c235e0695259ca5e4783af4fb\">\n#top .togglecontainer.av-lvkvei80-3845649c235e0695259ca5e4783af4fb p.toggler{\nfont-size:35px;\n}\n#top .togglecontainer.av-lvkvei80-3845649c235e0695259ca5e4783af4fb .toggle_wrap .toggle_content{\nfont-size:30px;\n}\n<\/style>\n<div  class='togglecontainer av-lvkvei80-3845649c235e0695259ca5e4783af4fb av-elegant-toggle  avia-builder-el-44  el_after_av_heading  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-ym05z-eff7a1ca458909bf75447ea7cbb3a247'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-14' data-fake-id='#toggle-id-14' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-14' data-slide-speed=\"200\" data-title=\"Migliore interazione\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Migliore interazione\" data-aria_expanded=\"Click to collapse: Migliore interazione\">Mejor interacci\u00f3n<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-14' aria-labelledby='toggle-toggle-id-14' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>Un voicebot IVR o interactiva ofrece una forma de comunicaci\u00f3n m\u00e1s suave y m\u00e1s r\u00e1pido al proporcionar una manera r\u00e1pida y eficiente la informaci\u00f3n que los cuidadores necesitan, sin obligarlos a buscar y visualizar los documentos, informes, notas, cl\u00ednica en la carpeta, etc.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-pqbof-904595c7e75a46ac5e4ede2bc2f70747'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-15' data-fake-id='#toggle-id-15' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-15' data-slide-speed=\"200\" data-title=\"Elevata disponibilit\u00e0\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Elevata disponibilit\u00e0\" data-aria_expanded=\"Click to collapse: Elevata disponibilit\u00e0\">Alta disponibilidad<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-15' aria-labelledby='toggle-toggle-id-15' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>El sistema se basa en voicebot es esencialmente siempre disponible las 24 horas del d\u00eda y 7 de las 7, por lo que los trabajadores de la salud pueden obtener respuestas a sus preguntas y sus problemas las 24 horas sobre 24, 7 d\u00edas sobre 7, sin tener que perder el tiempo buscando el finormazioni por los archivos electr\u00f3nicos est\u00e1n disponibles. Este elemento es muy importante en situaciones cr\u00edticas o de emergencia en tiempos dif\u00edciles, cuando es complejo para ser capaz de contar con el apoyo de la mayor\u00eda de los colegas del departamento o de otras estructuras.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-jo4qn-4519c2ee4b03fdcc317a0c924fc97f5e'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Todo} \"  ><p id='toggle-toggle-id-16' data-fake-id='#toggle-id-16' class='toggler  av-title-above'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-16' data-slide-speed=\"200\" data-title=\"Miglioramento degli outcome clinici\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Miglioramento degli outcome clinici\" data-aria_expanded=\"Click to collapse: Miglioramento degli outcome clinici\">La mejora de los resultados cl\u00ednicos<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-16' aria-labelledby='toggle-toggle-id-16' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color'  itemprop=\"text\" ><p>El sistema se basa en voicebot puede ayudar a reducir los tiempos de curaci\u00f3n y mejorar el nivel de precisi\u00f3n de la hip\u00f3tesis de diagnnostiche de apoyo y un mejor nivel de conocimiento en la elecci\u00f3n de la v\u00eda de atenci\u00f3n y terapias farmacol\u00f3gicas pueden ser m\u00e1s convenientes en un caso concreto.<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-e1l2n-79e17aa62d5f97b142a6843ead03f663\">\n#top .hr.hr-invisible.av-e1l2n-79e17aa62d5f97b142a6843ead03f663{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-e1l2n-79e17aa62d5f97b142a6843ead03f663 hr-invisible  avia-builder-el-45  el_after_av_one_full  avia-builder-el-last'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-92q13-3e24f2b721a828fd15391607c9d6b0bf\">\n.avia-section.av-92q13-3e24f2b721a828fd15391607c9d6b0bf{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.talence.it\/wp-content\/uploads\/2024\/01\/rete-2.jpg);\nbackground-position:50% 50%;\nbackground-attachment:fixed;\n}\n.avia-section.av-92q13-3e24f2b721a828fd15391607c9d6b0bf .av-section-color-overlay{\nopacity:0.6;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_6'  class='avia-section av-92q13-3e24f2b721a828fd15391607c9d6b0bf main_color avia-section-huge avia-no-border-styling  avia-builder-el-46  el_after_av_section  avia-builder-el-last  avia-full-stretch avia-bg-style-fixed av-section-color-overlay-active container_wrap fullsize'  data-section-bg-repeat='stretch'><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-591'><div class='entry-content-wrapper clearfix'><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interrogazione dei dati sanitari - Talence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.talence.it\/es\/2024\/04\/interrogazione-dei-dati-sanitari\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interrogazione dei dati sanitari - Talence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.talence.it\/es\/2024\/04\/interrogazione-dei-dati-sanitari\/\" \/>\n<meta property=\"og:site_name\" content=\"Talence\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T09:51:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T11:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1880\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Cuccarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Cuccarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/\"},\"author\":{\"name\":\"Andrea Cuccarini\",\"@id\":\"https:\/\/www.talence.it\/#\/schema\/person\/77eeadb801834a5bedcafc6dc15b6401\"},\"headline\":\"Interrogazione dei dati sanitari\",\"datePublished\":\"2024-04-29T09:51:35+00:00\",\"dateModified\":\"2024-04-29T11:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/\"},\"wordCount\":11838,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.talence.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/\",\"url\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/\",\"name\":\"Interrogazione dei dati sanitari - Talence\",\"isPartOf\":{\"@id\":\"https:\/\/www.talence.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg\",\"datePublished\":\"2024-04-29T09:51:35+00:00\",\"dateModified\":\"2024-04-29T11:51:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage\",\"url\":\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg\",\"contentUrl\":\"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg\",\"width\":1880,\"height\":624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.talence.it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interrogazione dei dati sanitari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.talence.it\/#website\",\"url\":\"https:\/\/www.talence.it\/\",\"name\":\"Talence\",\"description\":\"DIgital intelligence\",\"publisher\":{\"@id\":\"https:\/\/www.talence.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.talence.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.talence.it\/#organization\",\"name\":\"Talence\",\"url\":\"https:\/\/www.talence.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.talence.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.talence.it\/wp-content\/uploads\/2023\/12\/AS-Color-logo-no-background.png\",\"contentUrl\":\"https:\/\/www.talence.it\/wp-content\/uploads\/2023\/12\/AS-Color-logo-no-background.png\",\"width\":3149,\"height\":1136,\"caption\":\"Talence\"},\"image\":{\"@id\":\"https:\/\/www.talence.it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.talence.it\/#\/schema\/person\/77eeadb801834a5bedcafc6dc15b6401\",\"name\":\"Andrea Cuccarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.talence.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/152064668c1e3bb4f3e78242bba075a288ca395795c248b4e0ad0b0696f09209?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/152064668c1e3bb4f3e78242bba075a288ca395795c248b4e0ad0b0696f09209?s=96&d=mm&r=g\",\"caption\":\"Andrea Cuccarini\"},\"url\":\"https:\/\/www.talence.it\/es\/author\/admin-andy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interrogazione dei dati sanitari - Talence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.talence.it\/es\/2024\/04\/interrogazione-dei-dati-sanitari\/","og_locale":"es_ES","og_type":"article","og_title":"Interrogazione dei dati sanitari - Talence","og_url":"https:\/\/www.talence.it\/es\/2024\/04\/interrogazione-dei-dati-sanitari\/","og_site_name":"Talence","article_published_time":"2024-04-29T09:51:35+00:00","article_modified_time":"2024-04-29T11:51:28+00:00","og_image":[{"width":1880,"height":624,"url":"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg","type":"image\/jpeg"}],"author":"Andrea Cuccarini","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andrea Cuccarini","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#article","isPartOf":{"@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/"},"author":{"name":"Andrea Cuccarini","@id":"https:\/\/www.talence.it\/#\/schema\/person\/77eeadb801834a5bedcafc6dc15b6401"},"headline":"Interrogazione dei dati sanitari","datePublished":"2024-04-29T09:51:35+00:00","dateModified":"2024-04-29T11:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/"},"wordCount":11838,"commentCount":0,"publisher":{"@id":"https:\/\/www.talence.it\/#organization"},"image":{"@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/","url":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/","name":"Interrogazione dei dati sanitari - Talence","isPartOf":{"@id":"https:\/\/www.talence.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage"},"image":{"@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg","datePublished":"2024-04-29T09:51:35+00:00","dateModified":"2024-04-29T11:51:28+00:00","breadcrumb":{"@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#primaryimage","url":"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg","contentUrl":"https:\/\/www.talence.it\/wp-content\/uploads\/2024\/04\/voicebot.jpg","width":1880,"height":624},{"@type":"BreadcrumbList","@id":"https:\/\/www.talence.it\/2024\/04\/interrogazione-dei-dati-sanitari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.talence.it\/home\/"},{"@type":"ListItem","position":2,"name":"Interrogazione dei dati sanitari"}]},{"@type":"WebSite","@id":"https:\/\/www.talence.it\/#website","url":"https:\/\/www.talence.it\/","name":"Talence","description":"DIgital intelligence","publisher":{"@id":"https:\/\/www.talence.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.talence.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.talence.it\/#organization","name":"Talence","url":"https:\/\/www.talence.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.talence.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.talence.it\/wp-content\/uploads\/2023\/12\/AS-Color-logo-no-background.png","contentUrl":"https:\/\/www.talence.it\/wp-content\/uploads\/2023\/12\/AS-Color-logo-no-background.png","width":3149,"height":1136,"caption":"Talence"},"image":{"@id":"https:\/\/www.talence.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.talence.it\/#\/schema\/person\/77eeadb801834a5bedcafc6dc15b6401","name":"Andrea Cuccarini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.talence.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/152064668c1e3bb4f3e78242bba075a288ca395795c248b4e0ad0b0696f09209?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/152064668c1e3bb4f3e78242bba075a288ca395795c248b4e0ad0b0696f09209?s=96&d=mm&r=g","caption":"Andrea Cuccarini"},"url":"https:\/\/www.talence.it\/es\/author\/admin-andy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/posts\/591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/comments?post=591"}],"version-history":[{"count":35,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/posts\/591\/revisions"}],"predecessor-version":[{"id":815,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/posts\/591\/revisions\/815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/media\/814"}],"wp:attachment":[{"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/media?parent=591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/categories?post=591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.talence.it\/es\/wp-json\/wp\/v2\/tags?post=591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}